{"id":46931,"date":"2026-08-27T08:34:38","date_gmt":"2026-08-27T06:34:38","guid":{"rendered":"https:\/\/ijg.net\/research\/?p=46931"},"modified":"2026-08-27T08:34:39","modified_gmt":"2026-08-27T06:34:39","slug":"ijg-daily-27-august-2026","status":"publish","type":"post","link":"https:\/\/ijg.net\/research\/ijg-daily-27-august-2026\/","title":{"rendered":"IJG Daily 27 August 2026"},"content":{"rendered":"<iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Fijg.net%2Fresearch%2Fwp-content%2Fuploads%2FIJG-Daily-270826.pdf&hl=en_US&embedded=true\" class=\"gde-frame\" style=\"width:100%; height:500px; border: none;\" scrolling=\"no\"><\/iframe>\n<p class=\"gde-text\"><a href=\"https:\/\/ijg.net\/research\/wp-content\/uploads\/IJG-Daily-270826.pdf\" class=\"gde-link\">Download (PDF, 1.19MB)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,17],"tags":[],"class_list":["post-46931","post","type-post","status-publish","format-standard","hentry","category-ijgdaily","category-regularresearch"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/posts\/46931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/comments?post=46931"}],"version-history":[{"count":1,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/posts\/46931\/revisions"}],"predecessor-version":[{"id":46935,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/posts\/46931\/revisions\/46935"}],"wp:attachment":[{"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/media?parent=46931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/categories?post=46931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ijg.net\/research\/wp-json\/wp\/v2\/tags?post=46931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}